{"id":213,"date":"2014-01-12T10:34:38","date_gmt":"2014-01-12T09:34:38","guid":{"rendered":"http:\/\/www.locationencorse.eu\/blog\/?p=213"},"modified":"2020-02-25T08:51:22","modified_gmt":"2020-02-25T07:51:22","slug":"la-plongee-en-corse","status":"publish","type":"post","link":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/","title":{"rendered":"La plong\u00e9e en Corse"},"content":{"rendered":"<p>La plong\u00e9e en Corse vous incite \u00e0 plonger dans l\u2019 eau turquoise n\u2019est pas seulement une invitation au farniente. Elle vous emporte dans un tourbillon d\u2019activit\u00e9s \u00e0 sensations \u2026 plus ou moins fortes!<\/p>\n<p>La grande limpidit\u00e9 des eaux Corses, de tr\u00e8s beaux sites et une eau transparente et chaude. La r\u00e9serve de la Scandola \u00e0 Porto offre aussi des plong\u00e9es inoubliables,.<\/p>\n<p>Si vous n\u2019avez pas le choix que de partir en Corse en juillet ou pire en ao\u00fbt, essayer de r\u00e9server vos plong\u00e9es \u00e0 l\u2019avance, \u00e0 la derni\u00e8re minute, il n\u2019y a plus toujours ce qu\u2019on aurait souhait\u00e9.<\/p>\n<p>Plong\u00e9e tout niveau et remont\u00e9e douce dans une sorte de grand goulot tr\u00e8s riche au niveau faune et flore. En \u00e9t\u00e9, il y a possibilit\u00e9 de faire du snorkeling pour les non-plongeurs.<\/p>\n<p>D\u00e9couvrez la plong\u00e9e en Corse du Sud dans le parc marin international des bouches de Bonifacio. Apr\u00e8s les r\u00e9serves naturelles de Scandola, des \u00eeles des Moine, des \u00eeles Lavezzi, venez d\u00e9couvrir les fonds sous marins des \u00eeles Cerbicales, cela vaut le coup aussi.<\/p>\n<p>Nul besoin de mat\u00e9riel lourd : un masque, un tuba et une paire de palmes, c\u2019est tout, pour faire du snorkeling,&nbsp; Il s\u2019agit ni plus ni moins de randonn\u00e9es palm\u00e9es, pour un aper\u00e7u des fonds marins. C\u2019est une activit\u00e9 tr\u00e8s agr\u00e9able \u00e0 pratiquer en famille, pour initier les enfants \u00e0 la biologie des fonds marins. Beaucoup de passions et de vocations sont n\u00e9es d\u2019un bapt\u00eame de plong\u00e9e dans les eaux cristallines corses, riches en \u00e9paves, r\u00e9cifs et poissons multicolores.<\/p>\n<p>En choisissant de s\u00e9journer dans une location de&nbsp;<strong>vacances corse&nbsp;<\/strong>sur la c\u00f4te \u00e0 proximit\u00e9 de clubs de plong\u00e9e, amateurs et initi\u00e9s, pourront profiter de la mer et de ses tr\u00e9sors.<\/p>\n<p>De bons centres de plong\u00e9es vous feront passer de tr\u00e8s bons moments, environ 80 centres en corse.<\/p>\n<p>Les fonds sous marins Corse riches en histoire.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/6UcAY5IHx-A\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: left;\">Quelques sites de <a title=\"plong\u00e9e en corse\" href=\"https:\/\/www.locationencorse.eu\/activites-loisirs-corse\/mer-et-plages\/\" target=\"_blank\" rel=\"noopener\">plong\u00e9e sous marine&nbsp;en corse<\/a>&nbsp;pour d\u00e9couvrir une exp\u00e9rience unique sous l&rsquo;eau.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La plong\u00e9e en Corse vous incite \u00e0 plonger dans l\u2019 eau turquoise n\u2019est pas seulement une invitation au farniente. Elle vous emporte dans un tourbillon d\u2019activit\u00e9s \u00e0 sensations \u2026 plus ou moins fortes! La grande limpidit\u00e9 des eaux Corses, de &hellip; <a href=\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[161,157],"tags":[86,23],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La plong\u00e9e en Corse - D\u00e9couverte des fonds marins corses<\/title>\n<meta name=\"description\" content=\"L\u2019eau turquoise de la m\u00e9diterran\u00e9e vous invite \u00e0 la plong\u00e9e en corse dans un tourbillon d&#039;activit\u00e9s avec la d\u00e9couverte des magnifiques fonds marins color\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La plong\u00e9e en Corse - D\u00e9couverte des fonds marins corses\" \/>\n<meta property=\"og:description\" content=\"L\u2019eau turquoise de la m\u00e9diterran\u00e9e vous invite \u00e0 la plong\u00e9e en corse dans un tourbillon d&#039;activit\u00e9s avec la d\u00e9couverte des magnifiques fonds marins color\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/\" \/>\n<meta property=\"og:site_name\" content=\"La Corse\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/locationencorse.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-12T09:34:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-25T07:51:22+00:00\" \/>\n<meta name=\"author\" content=\"Newchallenge\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newchallenge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/\",\"url\":\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/\",\"name\":\"La plong\u00e9e en Corse - D\u00e9couverte des fonds marins corses\",\"isPartOf\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#website\"},\"datePublished\":\"2014-01-12T09:34:38+00:00\",\"dateModified\":\"2020-02-25T07:51:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c\"},\"description\":\"L\u2019eau turquoise de la m\u00e9diterran\u00e9e vous invite \u00e0 la plong\u00e9e en corse dans un tourbillon d'activit\u00e9s avec la d\u00e9couverte des magnifiques fonds marins color\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.locationencorse.eu\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plong\u00e9e en Corse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#website\",\"url\":\"https:\/\/www.locationencorse.eu\/blog\/\",\"name\":\"La Corse\",\"description\":\"Vacances en Corse sur \u00cele de beaut\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.locationencorse.eu\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c\",\"name\":\"Newchallenge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g\",\"caption\":\"Newchallenge\"},\"sameAs\":[\"http:\/\/www.locationencorse.eu\",\"https:\/\/www.facebook.com\/locationencorse.eu\/\"],\"url\":\"https:\/\/www.locationencorse.eu\/blog\/author\/martinenewchallenge-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La plong\u00e9e en Corse - D\u00e9couverte des fonds marins corses","description":"L\u2019eau turquoise de la m\u00e9diterran\u00e9e vous invite \u00e0 la plong\u00e9e en corse dans un tourbillon d'activit\u00e9s avec la d\u00e9couverte des magnifiques fonds marins color\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/","og_locale":"fr_FR","og_type":"article","og_title":"La plong\u00e9e en Corse - D\u00e9couverte des fonds marins corses","og_description":"L\u2019eau turquoise de la m\u00e9diterran\u00e9e vous invite \u00e0 la plong\u00e9e en corse dans un tourbillon d'activit\u00e9s avec la d\u00e9couverte des magnifiques fonds marins color\u00e9s.","og_url":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/","og_site_name":"La Corse","article_author":"https:\/\/www.facebook.com\/locationencorse.eu\/","article_published_time":"2014-01-12T09:34:38+00:00","article_modified_time":"2020-02-25T07:51:22+00:00","author":"Newchallenge","twitter_misc":{"\u00c9crit par":"Newchallenge","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/","url":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/","name":"La plong\u00e9e en Corse - D\u00e9couverte des fonds marins corses","isPartOf":{"@id":"https:\/\/www.locationencorse.eu\/blog\/#website"},"datePublished":"2014-01-12T09:34:38+00:00","dateModified":"2020-02-25T07:51:22+00:00","author":{"@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c"},"description":"L\u2019eau turquoise de la m\u00e9diterran\u00e9e vous invite \u00e0 la plong\u00e9e en corse dans un tourbillon d'activit\u00e9s avec la d\u00e9couverte des magnifiques fonds marins color\u00e9s.","breadcrumb":{"@id":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.locationencorse.eu\/blog\/la-plongee-en-corse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.locationencorse.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"La plong\u00e9e en Corse"}]},{"@type":"WebSite","@id":"https:\/\/www.locationencorse.eu\/blog\/#website","url":"https:\/\/www.locationencorse.eu\/blog\/","name":"La Corse","description":"Vacances en Corse sur \u00cele de beaut\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.locationencorse.eu\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c","name":"Newchallenge","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g","caption":"Newchallenge"},"sameAs":["http:\/\/www.locationencorse.eu","https:\/\/www.facebook.com\/locationencorse.eu\/"],"url":"https:\/\/www.locationencorse.eu\/blog\/author\/martinenewchallenge-fr\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/213"}],"collection":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":13,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"predecessor-version":[{"id":7356,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/213\/revisions\/7356"}],"wp:attachment":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}