{"id":1251,"date":"2014-02-14T08:47:29","date_gmt":"2014-02-14T07:47:29","guid":{"rendered":"http:\/\/www.locationencorse.eu\/blog\/?p=1251"},"modified":"2014-02-24T20:26:43","modified_gmt":"2014-02-24T19:26:43","slug":"les-fetes-religieuses-en-corse","status":"publish","type":"post","link":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/","title":{"rendered":"Les f\u00eates religieuses en Corse"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\"><span style=\"color: #ff6600;\">Les f\u00eates religieuses hautes en couleur<\/span><\/span><\/strong><\/p>\n<p>SI vous s\u00e9journez en Corse du Sud dans une <a href=\"http:\/\/www.locationencorse.eu\/rec\/?destination=Ajaccio\" target=\"_blank\">location ajaccio<\/a>, vous remarquerez peut-\u00eatre plus qu&rsquo;ailleurs, l&rsquo;expression toujours pr\u00e9sente, malgr\u00e9 les assauts du modernisme, du sentiment religieux. De nombreuses f\u00eates votives sont c\u00e9l\u00e9br\u00e9es dans une paroisse, une ville ou bien une \u00ab\u00a0pi\u00e8ve\u00a0\u00bb (ancienne entit\u00e9 administrative correspondant \u00e0 un d\u00e9coupage eccl\u00e9siastique). Des processions en l&rsquo;honneur de la Vierge Marie, patronne de la Corse, ou bien des Saints plus particuli\u00e8rement honor\u00e9s et estim\u00e9s des autochtones : St Roch, St Dominique, St Antoine, St Barth\u00e9l\u00e9my ou St Th\u00e9ophile&#8230;.. D\u00e9filent dans les rues \u00e0 l&rsquo;occasion de leurs f\u00eates.<br \/>\nEn Corse du Sud, la semaine Sainte, avant P\u00e2ques, est marqu\u00e9e par des manifestations exceptionnelles, hautes en couleurs et en ferveur, \u00e0 Bonifacio et \u00e0 Sart\u00e8ne.<br \/>\nLe soir du Vendredi Saint, les 5 confr\u00e9ries religieuses que compte la Citadelle du Sud organisent une procession nocturne. Des sculptures de bois, dont certaines p\u00e8sent plus d&rsquo;une tonne, sont port\u00e9es \u00e0 dos d&rsquo;homme \u00e0 travers les rues escarp\u00e9es de la vielle ville. Ces \u0153uvres datant du XIV \u00e8me et XV\u00e8me si\u00e8cle \u00e9voquent le martyre de Saint Barth\u00e9l\u00e9my ou de Saint Jean-Baptiste, ou plus souvent, les sc\u00e8nes de la Passion du Christ. Chacun se pressera pour porter, \u00e0 son tour, ces sculptures en \u00e9vitant de les faire basculer. C&rsquo;est \u00e0 Sart\u00e8ne, toujours la nuit du vendredi Saint, que se d\u00e9roule la c\u00e9r\u00e9monie la plus dramatique : la <strong>procession du \u00ab\u00a0Catenacci\u00f9\u00a0\u00bb \u00ab\u00a0Encha\u00een\u00e9\u00a0\u00bb.<\/strong><\/p>\n<p style=\"text-align: left;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/y7BnA-c5OoI?rel=0\" height=\"315\" width=\"420\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><br \/>\nA l&rsquo;autre extr\u00e9mit\u00e9 du d\u00e9partement, \u00e0 Carg\u00e8se, les f\u00eates et offices religieux pr\u00e9sentent parfois la particularit\u00e9 de se d\u00e9rouler selon le rite latin dans l&rsquo;Eglise Ste Marie, et, suivant le rite Catholique Grec dans une autre \u00e9glise, \u00e9galement d\u00e9di\u00e9e \u00e0 la Vierge, construite en face de la premi\u00e8re. En effet, une partie de la population de Carg\u00e8se est d&rsquo;origine Grecque. En 1676, les habitants de Magne dans le P\u00e9loponn\u00e8se, pr\u00e9f\u00e9rant l&rsquo;exil \u00e0 l&rsquo;occupation Turque, obtinrent de <a href=\"http:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/olympus-digital-camera\/\" rel=\"attachment wp-att-1260\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-thumbnail wp-image-1260\" alt=\"OLYMPUS DIGITAL CAMERA\" src=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/cargese-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a>l&rsquo;administration G\u00e9noise, l&rsquo;autorisation de s&rsquo;installer en Corse, en un lieu proche de l&rsquo;actuelle<strong> Carg\u00e8se<\/strong>. Voil\u00e0 pourquoi il arrive aux touristes de croiser un Pope dans les rues de cette charmante station baln\u00e9aire&#8230;.<br \/>\nLes offices de la semaine Sainte c\u00e9l\u00e9br\u00e9s suivant les coutumes Byzantines sont particuli\u00e8rement \u00e9mouvants.<br \/>\nAjaccio, la capitale, se signale par deux processions solennelles dans les rues, sans autre particularit\u00e9 que le nombre \u00e9lev\u00e9 de participants : celle du Vendredi Saint et celle de l&rsquo;Assomption, le 15 Ao\u00fbt. Cette f\u00eate religieuse co\u00efncide avec la f\u00eate de Napol\u00e9on, jour anniversaire de la naissance du futur Empereur, occasion de liesse populaire, de d\u00e9fil\u00e9s militaires, de reconstitutions historiques et vins d&rsquo;honneur.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/000_par123360.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-1257\" alt=\"15 aout fete des marie\" src=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/000_par123360.jpg\" width=\"640\" height=\"360\" srcset=\"https:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/000_par123360.jpg 640w, https:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/000_par123360-400x225.jpg 400w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Ces festivit\u00e9s \u00e0 ne pas manquer si vous vous trouvez dans la r\u00e9gion, que vous soyez croyants ou pas, pratiquants ou pas, mais simplement friands de culture et coutumes Corses.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Les f\u00eates religieuses hautes en couleur SI vous s\u00e9journez en Corse du Sud dans une location ajaccio, vous remarquerez peut-\u00eatre plus qu&rsquo;ailleurs, l&rsquo;expression toujours pr\u00e9sente, malgr\u00e9 les assauts du modernisme, du sentiment religieux. De nombreuses f\u00eates votives sont c\u00e9l\u00e9br\u00e9es dans &hellip; <a href=\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[157,162],"tags":[122,121],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les f\u00eates religieuses en Corse - La Corse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les f\u00eates religieuses en Corse - La Corse\" \/>\n<meta property=\"og:description\" content=\"Les f\u00eates religieuses hautes en couleur SI vous s\u00e9journez en Corse du Sud dans une location ajaccio, vous remarquerez peut-\u00eatre plus qu&rsquo;ailleurs, l&rsquo;expression toujours pr\u00e9sente, malgr\u00e9 les assauts du modernisme, du sentiment religieux. De nombreuses f\u00eates votives sont c\u00e9l\u00e9br\u00e9es dans &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/\" \/>\n<meta property=\"og:site_name\" content=\"La Corse\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/locationencorse.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-14T07:47:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-24T19:26:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/cargese-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Newchallenge\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newchallenge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/\",\"url\":\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/\",\"name\":\"Les f\u00eates religieuses en Corse - La Corse\",\"isPartOf\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#website\"},\"datePublished\":\"2014-02-14T07:47:29+00:00\",\"dateModified\":\"2014-02-24T19:26:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.locationencorse.eu\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les f\u00eates religieuses en Corse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#website\",\"url\":\"https:\/\/www.locationencorse.eu\/blog\/\",\"name\":\"La Corse\",\"description\":\"Vacances en Corse sur \u00cele de beaut\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.locationencorse.eu\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c\",\"name\":\"Newchallenge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g\",\"caption\":\"Newchallenge\"},\"sameAs\":[\"http:\/\/www.locationencorse.eu\",\"https:\/\/www.facebook.com\/locationencorse.eu\/\"],\"url\":\"https:\/\/www.locationencorse.eu\/blog\/author\/martinenewchallenge-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les f\u00eates religieuses en Corse - La Corse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/","og_locale":"fr_FR","og_type":"article","og_title":"Les f\u00eates religieuses en Corse - La Corse","og_description":"Les f\u00eates religieuses hautes en couleur SI vous s\u00e9journez en Corse du Sud dans une location ajaccio, vous remarquerez peut-\u00eatre plus qu&rsquo;ailleurs, l&rsquo;expression toujours pr\u00e9sente, malgr\u00e9 les assauts du modernisme, du sentiment religieux. De nombreuses f\u00eates votives sont c\u00e9l\u00e9br\u00e9es dans &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/","og_site_name":"La Corse","article_author":"https:\/\/www.facebook.com\/locationencorse.eu\/","article_published_time":"2014-02-14T07:47:29+00:00","article_modified_time":"2014-02-24T19:26:43+00:00","og_image":[{"url":"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/cargese-150x150.jpg"}],"author":"Newchallenge","twitter_misc":{"\u00c9crit par":"Newchallenge","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/","url":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/","name":"Les f\u00eates religieuses en Corse - La Corse","isPartOf":{"@id":"https:\/\/www.locationencorse.eu\/blog\/#website"},"datePublished":"2014-02-14T07:47:29+00:00","dateModified":"2014-02-24T19:26:43+00:00","author":{"@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c"},"breadcrumb":{"@id":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.locationencorse.eu\/blog\/les-fetes-religieuses-en-corse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.locationencorse.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"Les f\u00eates religieuses en Corse"}]},{"@type":"WebSite","@id":"https:\/\/www.locationencorse.eu\/blog\/#website","url":"https:\/\/www.locationencorse.eu\/blog\/","name":"La Corse","description":"Vacances en Corse sur \u00cele de beaut\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.locationencorse.eu\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c","name":"Newchallenge","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g","caption":"Newchallenge"},"sameAs":["http:\/\/www.locationencorse.eu","https:\/\/www.facebook.com\/locationencorse.eu\/"],"url":"https:\/\/www.locationencorse.eu\/blog\/author\/martinenewchallenge-fr\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/1251"}],"collection":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/comments?post=1251"}],"version-history":[{"count":9,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/1251\/revisions"}],"predecessor-version":[{"id":1263,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/1251\/revisions\/1263"}],"wp:attachment":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/media?parent=1251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/categories?post=1251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/tags?post=1251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}