{"id":1120,"date":"2014-02-09T07:40:48","date_gmt":"2014-02-09T06:40:48","guid":{"rendered":"http:\/\/www.locationencorse.eu\/blog\/?p=1120"},"modified":"2014-04-21T11:50:15","modified_gmt":"2014-04-21T09:50:15","slug":"la-corse-la-faune-et-la-flore","status":"publish","type":"post","link":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/","title":{"rendered":"La Corse: la faune et la flore"},"content":{"rendered":"<p><strong><span style=\"color: #ff6600;\">La Corse\u00a0la faune et la flore:\u00a0\u00a0<\/span><\/strong><\/p>\n<p>De part sa situation g\u00e9ographique exceptionnelle, la Corse \u00ab\u00a0montagne dans la mer\u00a0\u00bb, compl\u00e8tement coup\u00e9e de toute attache avec les autres terres, d\u00e9veloppe une flore et une faune exceptionnelle. Faut-il alors s&rsquo;\u00e9tonner de voir tant de botanistes ou d&rsquo;ornithologues ou m\u00eame simplement de simples amoureux des plantes et des oiseaux s&rsquo;attacher \u00e0 cette \u00eele pour\u00a0nourrir leur passion? On peut dire que sur ce territoire on trouve tout : la roche, la mer, l&rsquo;humidit\u00e9 marine ramen\u00e9e par les vents, les eaux de sources, les oiseaux, la chaleur, la v\u00e9g\u00e9tation&#8230;. Comme le disait un insulaire, amoureux de sa Corse : tout n&rsquo;est \u00ab\u00a0qu&rsquo;offrandes\u00a0\u00bb de la nature. Les sites sauvegard\u00e9s ( gr\u00e2ce \u00e0 l&rsquo;institution du Parc Naturel R\u00e9gional, au Conservatoire du Littoral), \u00e0 eux seuls fournissent de quoi assouvir l&rsquo;amour de ces hommes et de ces femmes qui continuent \u00e0 lutter pour sauvegarder leur Paradis. M\u00eame si leurs actions ou leurs \u00e9tudes peuvent para\u00eetre d\u00e9risoires \u00e0 certains, comme le fait de compter le nombre de plantes qui prolif\u00e8rent chaque ann\u00e9e sur un minuscule territoire, elles sont toutes d&rsquo;une importance capitale pour les g\u00e9n\u00e9rations futures, pour la protection de notre \u00e9cosyst\u00e8me. Il faut reconna\u00eetre que de ces petites actions, minuscules gouttes d&rsquo;eau dans l&rsquo;oc\u00e9an, ce n&rsquo;est pas ce qui manque en Corse. Loin de les garder sous silence, elles commencent \u00e0 \u00eatre reconnues, m\u00e9diatis\u00e9es.<\/p>\n<p>C&rsquo;est ainsi qu&rsquo;on reconna\u00eet le travail acharn\u00e9 de cet homme parfois seul, parfois en petite \u00e9quipe, qui consacre sa vie \u00e0 sa passion : l&rsquo;observation des <a title=\"balbuzard\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Balbuzard_p%C3%AAcheur\">balbuzards<\/a>. <a href=\"http:\/\/www.locationencorse.eu\/blog\/la-corse-montagne-dans-la-mer\/balbuzard\/\" rel=\"attachment wp-att-1124\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-1124\" src=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/balbuzard.jpg\" alt=\"balbuzard\" width=\"290\" height=\"320\" \/><\/a>Ce rapace migrateur ou aigle p\u00eacheur vient nicher en Corse au printemps. Alors s\u00e9dentaire, il installe son large nid de branchages, d&rsquo;algues et de mousse \u00e0 la cime d&rsquo;un arbre ou sur un promontoire offrant une vue \u00e9tendue. Comme tous ces passionn\u00e9s, cet homme aide au recensement : 38 couples de balbuzards viennent se reproduire en Corse et jusqu&rsquo;\u00e0 pr\u00e9sent 8 dans la r\u00e9serve de Scandola.C&rsquo;est l\u00e0, dans cette r\u00e9serve, qu &lsquo;en observant r\u00e9cemment ces couples, notre d\u00e9fenseur de cette esp\u00e8ce tire la sonnette d&rsquo;alarme : une seule nich\u00e9e cette ann\u00e9e et sur cette nich\u00e9e un seul petit aigle a surv\u00e9cu. La\u00a0cause il l&rsquo;a conna\u00eet : l&rsquo;affluence des touristes, pendant la nich\u00e9e (parfois 300 bateaux par jour dans la r\u00e9serve) arrive \u00e0 perturber ces oiseaux et \u00e0 les faire fuir. Les observateurs imaginent toutes sortes de solutions pour pr\u00e9server l&rsquo;esp\u00e8ce, solutions plus ou moins risqu\u00e9es, les obligeant \u00e0 escalader des parois rocheuses, \u00e0 rester perch\u00e9s sur des postes d&rsquo;observation pendant des heures, \u00e0 essayer de capturer ces sp\u00e9cimens pour les munir de GPS afin de conna\u00eetre un peu mieux leurs migrations. Et quand il le faut, ils parcourent des kilom\u00e8tres \u00e0 la recherche d&rsquo;un endroit id\u00e9al pour leurs prot\u00e9g\u00e9s et lorsqu&rsquo;ils l&rsquo;ont trouv\u00e9, ils construisent patiemment un nid artificiel, le plus accueillant possible, le fixent sur un rocher \u00e9lev\u00e9, loin de toute agression possible, esp\u00e9rant ainsi voir nicher prochainement un autre couple de Balbuzards.<\/p>\n<p>On peut observer \u00e9galement, gr\u00e2ce \u00e0 la protection du Parc Naturel R\u00e9gional, la r\u00e9a climatisation des mouflons au c\u0153ur des montagnes les plus \u00e9lev\u00e9es de la haute vall\u00e9e d&rsquo;Asco, creus\u00e9e dans une masse de roches volcaniques, qui s&rsquo;\u00e9tend du Golfe de Girolata au village d&rsquo;Asco. Cette r\u00e9gion est devenue, sur pr\u00e9s de 300Ha, le domaine r\u00e9serv\u00e9 et prot\u00e9g\u00e9 des mouflons.<\/p>\n<p>Comment ne pas reconna\u00eetre aussi le travail de cette botaniste qui, patiemment, \u00e9tudie les richesses innombrables de ce maquis qui occupe la moiti\u00e9 de l&rsquo;\u00eele? Gr\u00e2ce au travail m\u00e9ticuleux de ces passionn\u00e9s, comme Laeticia Hugo, environ 150 plantes end\u00e9miques ont pu \u00eatre recens\u00e9es. L\u00e0 encore, le sud de la Corse et surtout les r\u00e9gions pr\u00e9serv\u00e9es, sont de v\u00e9ritables mannes pour ces passionn\u00e9s de plantes et de protection de la nature. L\u2019Immortelle, par exemple, offre ses parfums intenses d\u00e9s votre arriv\u00e9e\u00a0 sur l&rsquo;Ile. Certains disent qu\u2019ils reconnaissent l&rsquo;odeur de la Corse alors qu&rsquo;ils sont encore sur le bateau. Gr\u00e2ce \u00e0 son odeur unique vous saurez alors que votre arriv\u00e9e est proche.<a href=\"http:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/immortelle-2\/\" rel=\"attachment wp-att-1129\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-thumbnail wp-image-1129\" src=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/immortelle1-150x150.jpg\" alt=\"immortelle\" width=\"150\" height=\"150\" \/><\/a> De cette <a title=\"essence immortelle\" href=\"http:\/\/www.locationencorse.eu\/blog\/?p=980\"><strong>Immortelle<\/strong><\/a>, on en extrait des <a title=\"L\u2019immortelle Corse\" href=\"http:\/\/www.locationencorse.eu\/blog\/limmortelle-corse\/\" target=\"_blank\">huiles essentielles<\/a> rares et d\u2019une qualit\u00e9 unique. Essayez de la faire pousser ailleurs que sur son sol natal cette plante n&rsquo;aura plus les m\u00eames vertus et pourra m\u00eame devenir nocive. C&rsquo;est dans la r\u00e9gion de Cania, qu&rsquo;on trouve une Orchid\u00e9e sauvage appel\u00e9e aussi Papillon et \u00e0 La Trinit\u00e9 pr\u00e9s de Bonifacio, une autre plante tr\u00e8s rare (une centaine seulement) fait l&rsquo;objet de toutes les attentions de cette botaniste passionn\u00e9e. Avec son \u00e9quipe, elle ne compte pas ses heures, escaladant des roches p\u00e9rilleuses, guettant \u00e9merveill\u00e9e, la moindre pousse nouvelle, signe accueilli comme l&rsquo;arriv\u00e9e d&rsquo;un nouveau-n\u00e9, t\u00e9moin de la bonne reproduction de l&rsquo;esp\u00e8ce end\u00e9mique.<\/p>\n<p>Une autre Orchid\u00e9e ou \u00ab\u00a0Sabot de V\u00e9nus\u00a0\u00bb, se rencontre dans les montagnes, o\u00f9 elle vit dans les bois, dans les h\u00eatraies surtout ou dans les hauts p\u00e2turages aux terres peu fertiles. Elle s&rsquo;\u00e9panouit entre Mai et Juillet en une floraison jaune, teint\u00e9e de vert.<\/p>\n<p>Sept sortes de thym sont aussi recens\u00e9es, tous diff\u00e9rents de celui du continent.<\/p>\n<p>A Lama, en Balagne, les oliviers aussi font l&rsquo;objet de toutes les attentions de ces passionn\u00e9s de la Flore.<\/p>\n<p>Les fonds marins du Golfe de Porto, riches eux aussi d&rsquo;une flore et d&rsquo;une faune rares, font l&rsquo;objet de recherches pointues afin de les prot\u00e9ger. On dit qu&rsquo;ici, les poissons y meurent de vieillesse!!! Il est fr\u00e9quent de voir arriver des \u00e9quipes, venant d&rsquo;Italie, d&rsquo;Espagne ou d&rsquo;ailleurs, pour \u00e9tudier des colonies de coraux particuli\u00e8rement rares, rouges ou blancs, \u00e0 faible profondeur (20m au lieu de 100 m habituellement).<\/p>\n<p>Si vous aussi vous partagez les m\u00eames passions et si vous voulez faire partie de ces d\u00e9fenseurs qui luttent contre les agressions de toute nature pouvant d\u00e9truire ces laboratoires vivants, alors posez vos bagages quelque part pr\u00e9s de ces lieux privil\u00e9gies (<a title=\"location ile rousse\" href=\"http:\/\/www.locationencorse.eu\/rec\/?destination=L%27ile+Rousse\">location \u00eele Rousse<\/a>, <a title=\"location calvi\" href=\"http:\/\/www.locationencorse.eu\/rec\/?destination=Calvi\">location Calvi<\/a>, <a title=\"location bonifacio\" href=\"http:\/\/www.locationencorse.eu\/rec\/?destination=Bonifacio\">location Bonifacio<\/a>&#8230;). Allez \u00e0 la rencontre de ces personnes exceptionnelles, corses pour la plupart; elles seront heureuses de partager l&rsquo;Amour pour leur \u00eele, leur passion pour la Nature, leur savoir- faire et les r\u00e9sultats de leurs recherches avec vous. Soyez les bienvenus dans ce Paradis, mais surtout respectez le, il saura vous le rendre et en faire b\u00e9n\u00e9ficier les g\u00e9n\u00e9rations futures.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La Corse\u00a0la faune et la flore:\u00a0\u00a0 De part sa situation g\u00e9ographique exceptionnelle, la Corse \u00ab\u00a0montagne dans la mer\u00a0\u00bb, compl\u00e8tement coup\u00e9e de toute attache avec les autres terres, d\u00e9veloppe une flore et une faune exceptionnelle. Faut-il alors s&rsquo;\u00e9tonner de voir tant &hellip; <a href=\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[157,1,163],"tags":[165],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Corse: la faune et la flore - La Corse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Corse: la faune et la flore - La Corse\" \/>\n<meta property=\"og:description\" content=\"La Corse\u00a0la faune et la flore:\u00a0\u00a0 De part sa situation g\u00e9ographique exceptionnelle, la Corse \u00ab\u00a0montagne dans la mer\u00a0\u00bb, compl\u00e8tement coup\u00e9e de toute attache avec les autres terres, d\u00e9veloppe une flore et une faune exceptionnelle. Faut-il alors s&rsquo;\u00e9tonner de voir tant &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/\" \/>\n<meta property=\"og:site_name\" content=\"La Corse\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/locationencorse.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-09T06:40:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-21T09:50:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/balbuzard.jpg\" \/>\n<meta name=\"author\" content=\"Newchallenge\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newchallenge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/\",\"url\":\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/\",\"name\":\"La Corse: la faune et la flore - La Corse\",\"isPartOf\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#website\"},\"datePublished\":\"2014-02-09T06:40:48+00:00\",\"dateModified\":\"2014-04-21T09:50:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.locationencorse.eu\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Corse: la faune et la flore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#website\",\"url\":\"https:\/\/www.locationencorse.eu\/blog\/\",\"name\":\"La Corse\",\"description\":\"Vacances en Corse sur \u00cele de beaut\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.locationencorse.eu\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c\",\"name\":\"Newchallenge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g\",\"caption\":\"Newchallenge\"},\"sameAs\":[\"http:\/\/www.locationencorse.eu\",\"https:\/\/www.facebook.com\/locationencorse.eu\/\"],\"url\":\"https:\/\/www.locationencorse.eu\/blog\/author\/martinenewchallenge-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Corse: la faune et la flore - La Corse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/","og_locale":"fr_FR","og_type":"article","og_title":"La Corse: la faune et la flore - La Corse","og_description":"La Corse\u00a0la faune et la flore:\u00a0\u00a0 De part sa situation g\u00e9ographique exceptionnelle, la Corse \u00ab\u00a0montagne dans la mer\u00a0\u00bb, compl\u00e8tement coup\u00e9e de toute attache avec les autres terres, d\u00e9veloppe une flore et une faune exceptionnelle. Faut-il alors s&rsquo;\u00e9tonner de voir tant &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/","og_site_name":"La Corse","article_author":"https:\/\/www.facebook.com\/locationencorse.eu\/","article_published_time":"2014-02-09T06:40:48+00:00","article_modified_time":"2014-04-21T09:50:15+00:00","og_image":[{"url":"http:\/\/www.locationencorse.eu\/blog\/wp-content\/uploads\/2014\/02\/balbuzard.jpg"}],"author":"Newchallenge","twitter_misc":{"\u00c9crit par":"Newchallenge","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/","url":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/","name":"La Corse: la faune et la flore - La Corse","isPartOf":{"@id":"https:\/\/www.locationencorse.eu\/blog\/#website"},"datePublished":"2014-02-09T06:40:48+00:00","dateModified":"2014-04-21T09:50:15+00:00","author":{"@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c"},"breadcrumb":{"@id":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.locationencorse.eu\/blog\/la-corse-la-faune-et-la-flore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.locationencorse.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"La Corse: la faune et la flore"}]},{"@type":"WebSite","@id":"https:\/\/www.locationencorse.eu\/blog\/#website","url":"https:\/\/www.locationencorse.eu\/blog\/","name":"La Corse","description":"Vacances en Corse sur \u00cele de beaut\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.locationencorse.eu\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/4aa76a779067073b7500fdabe0a4a51c","name":"Newchallenge","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.locationencorse.eu\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad5f2a69d252f48179a77d3cb09e1fa7?s=96&r=g","caption":"Newchallenge"},"sameAs":["http:\/\/www.locationencorse.eu","https:\/\/www.facebook.com\/locationencorse.eu\/"],"url":"https:\/\/www.locationencorse.eu\/blog\/author\/martinenewchallenge-fr\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/1120"}],"collection":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/comments?post=1120"}],"version-history":[{"count":11,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/1120\/revisions"}],"predecessor-version":[{"id":3941,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/posts\/1120\/revisions\/3941"}],"wp:attachment":[{"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/media?parent=1120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/categories?post=1120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locationencorse.eu\/blog\/wp-json\/wp\/v2\/tags?post=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}